{"id":191,"date":"2021-08-31T20:17:46","date_gmt":"2021-08-31T18:17:46","guid":{"rendered":"https:\/\/planete-meteo.com\/blog\/?p=191"},"modified":"2021-09-01T16:50:01","modified_gmt":"2021-09-01T14:50:01","slug":"ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain","status":"publish","type":"post","link":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/","title":{"rendered":"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&rsquo;Ain"},"content":{"rendered":"\n<p>L&rsquo;\u00e9t\u00e9 2021 s&rsquo;ach\u00e8ve avec un mois d&rsquo;ao\u00fbt plus frais que la normale et tr\u00e8s peu de pluie pour les 20 derniers jours.<\/p>\n\n\n\n<p>Ce 31 ao\u00fbt marque la fin de l&rsquo;\u00e9t\u00e9 2021 du point de vue m\u00e9t\u00e9orologique, \u00e0 partir du 1er septembre nous commen\u00e7ons l&rsquo;<strong>automne<\/strong>. Mais attention, les fortes chaleurs sont toujours possibles, \u00e0 l&rsquo;image de ce qu&rsquo;on a connue ces derni\u00e8res ann\u00e9es les 30\u00b0C ont \u00e9t\u00e9 souvent d\u00e9pass\u00e9s m\u00eame plusieurs fois durant des \u00e9pisodes de chaleur tardif en septembre. Reste \u00e0 savoir si, \u00e0 l&rsquo;image de notre \u00e9t\u00e9 2021, ce mois de septembre retrouvera un mois de septembre un peu plus normal que les pr\u00e9c\u00e9dentes ann\u00e9es dans notre r\u00e9gion.<\/p>\n\n\n\n<p>Pour l&rsquo;ensemble des 3 mois de l&rsquo;\u00e9t\u00e9 2021 (juin\/juillet\/ao\u00fbt) la temp\u00e9rature moyenne \u00e0 Bourg en Bresse a \u00e9t\u00e9 de <span style=\"color:#FA5A24\"><strong>19,53\u00b0C<\/strong><\/span> soit <span style=\"color:#0247ea\"><strong>-0,3\u00b0C<\/strong><\/span> sous les normes, donc presque dans les normes d&rsquo;un \u00e9t\u00e9 dans notre r\u00e9gion m\u00eame si tr\u00e8s l\u00e9g\u00e8rement sous les normes.               20.3\u00b0C (<span style=\"color:#FA5A24\">+1.9\u00b0C<\/span>) pour Juin, 19.5\u00b0C (<span style=\"color:#0247ea\">-1.3\u00b0C<\/span>) pour Juillet, 18.8\u00b0C (<span style=\"color:#0247ea\">-1.5\u00b0C<\/span>) pour Ao\u00fbt.<\/p>\n\n\n\n<p>Incomparable avec les \u00e9t\u00e9 pr\u00e9c\u00e9dents que l&rsquo;on a connu ces 10 \u00e0 15 derni\u00e8res ann\u00e9es presque tous au-dessus des normales. A titre d&rsquo;exemple en 2018 \u00e0 Bourg en Bresse nous \u00e9tions \u00e0 <span style=\"color:#FA1809\">+1.8\u00b0C<\/span> au-dessus des normes, 2019 \u00e0 <span style=\"color:#FA1809\">+1.6\u00b0C<\/span> (le mois d&rsquo;aout \u00e0 +0.3\u00b0C compense les extr\u00eames de +2.4\u00b0C de juin et +2.2\u00b0C de juillet 2019) et <span style=\"color:#FA1809\">+1.0\u00b0C<\/span> pour l&rsquo;\u00e9t\u00e9 2020<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"912\" height=\"505\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png\" alt=\"\" class=\"wp-image-209\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png 912w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB-300x166.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB-768x425.png 768w\" sizes=\"auto, (max-width: 912px) 100vw, 912px\" \/><figcaption>Moyenne journali\u00e8re vs normes journali\u00e8res<\/figcaption><\/figure>\n\n\n\n<p>En revanche pour la pluie, tout autre constat, l&rsquo;\u00e9t\u00e9 a \u00e9t\u00e9 marqu\u00e9 par les mois de juin (pour l&rsquo;est du d\u00e9partement) et juillet tr\u00e8s pluvieux, et m\u00eame <strong>record <\/strong>depuis le d\u00e9but des mesures sur certaines stations en juillet. Fait rare, en raison de la persistance de fortes pr\u00e9cipitations, plusieurs rivi\u00e8res\/fleuves ont \u00e9t\u00e9 en <strong>crue <\/strong>vers la mi-juillet. <\/p>\n\n\n\n<p>Pour Bourg en Bresse le total de la pluviom\u00e9trie est de <span style=\"color:#A71FF0\"><strong>422.6 mm<\/strong><\/span> (<strong>91 mm<\/strong> en juin, <strong>262.6 mm <\/strong>en juillet et 69 mm en ao\u00fbt). Le mois d&rsquo;aout est venu l\u00e9g\u00e8rement compenser cette importante pluviom\u00e9trie avec un mois l\u00e9g\u00e8rement d\u00e9ficitaire et presque pas de pluie durant les 20 derniers jours du mois. En revanche il ne faudrait pas que cela dure, car encore en fin de p\u00e9riode estivale\/ d\u00e9but d&rsquo;automne la s\u00e9cheresse de surface pourrait rapidement apparaitre. On l&rsquo;a d\u00e9j\u00e0 connu lors des ann\u00e9es pr\u00e9c\u00e9dentes avec un mois de septembre compl\u00e8tement sec pouvait g\u00e9n\u00e9rer des s\u00e8cheresses importantes apr\u00e8s un \u00e9t\u00e9 correct.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"505\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/sMX6Hic.png\" alt=\"\" class=\"wp-image-207\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/sMX6Hic.png 899w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/sMX6Hic-300x169.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/sMX6Hic-768x431.png 768w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><figcaption>Cumul de pluie de l&rsquo;\u00e9t\u00e9 2021<\/figcaption><\/figure>\n\n\n\n<p>Au niveau du ressenti, cet \u00e9t\u00e9 restera un \u00e9t\u00e9 \u00ab\u00a0pourri\u00a0\u00bb et \u00ab\u00a0froid\u00a0\u00bb pour de nombreuses personnes, surtout avec la comparaison proche de notre m\u00e9moire que l&rsquo;on peut avoir avec ces 10 derni\u00e8res ann\u00e9es. Mais il faut le rappeler, l&rsquo;\u00e9t\u00e9 que l&rsquo;on vient de connaitre au niveau des temp\u00e9ratures auraient \u00e9t\u00e9 tout \u00e0 fait <strong>normal <\/strong>avant les ann\u00e9es 2000 et m\u00eame il aurait \u00e9t\u00e9 plus <strong>chaud <\/strong>avant 1980. Seul la pluie aura \u00e9t\u00e9 effectivement bien sup\u00e9rieure.<\/p>\n\n\n\n<p>Bilan climatique des diff\u00e9rents mois pour Bourg en Bresse :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Juin<\/pre>\n\n\n\n<p>Un premier mois qui marque l&rsquo;arriv\u00e9e en fanfare de l&rsquo;\u00e9t\u00e9 avec quelques jours chaud en d\u00e9but de mois puis une importante vague de chaleur tr\u00e8s pr\u00e9coce jusqu&rsquo;au 20 juin avec des temp\u00e9ratures tr\u00e8s largement au-dessus des normes, une vigilance orange canicule a \u00e9t\u00e9 m\u00eame mise en place pour le Rh\u00f4ne, jaune pour l&rsquo;Ain \u00e0 partir du 16. Des syst\u00e8mes perturb\u00e9s avec des orages parfois diluviens concernent l&rsquo;est du d\u00e9partement, les orages vont perdurer toute la fin du mois avec des temp\u00e9ratures en baisse. <\/p>\n\n\n\n<p>Temp\u00e9rature moyenne la plus chaude de cet \u00e9t\u00e9 avec 20.3\u00b0C (<strong>+1.9\u00b0C<\/strong> au dessus des normes)<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"499\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/DuP3LxF.png\" alt=\"\" class=\"wp-image-194\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/DuP3LxF.png 907w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/DuP3LxF-300x165.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/DuP3LxF-768x423.png 768w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><figcaption>Anomalie temp\u00e9rature juin 2021<\/figcaption><\/figure>\n\n\n\n<p>Au niveau des pr\u00e9cipitations, quelques orages, pluviom\u00e9trie proche des normales (pour cette partie du d\u00e9partement). En revanche pour le relief et proche de celui-ci avec les orages des cumuls proches des <strong>200 mm<\/strong> ont \u00e9t\u00e9 relev\u00e9s soit pr\u00e8s du double de la normale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"905\" height=\"502\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/W62JpPC.png\" alt=\"\" class=\"wp-image-195\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/W62JpPC.png 905w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/W62JpPC-300x166.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/W62JpPC-768x426.png 768w\" sizes=\"auto, (max-width: 905px) 100vw, 905px\" \/><figcaption>cumul pluie juin 2021<\/figcaption><\/figure>\n\n\n\n<pre class=\"wp-block-preformatted\">Juillet <\/pre>\n\n\n\n<p>Pour ce mois de juillet ce sont des vastes syst\u00e8mes d\u00e9pressionnaire qui viennent s&rsquo;isoler sur la France appel\u00e9s go\u00fbtes froides, ceux-ci g\u00e9n\u00e8re des importantes pr\u00e9cipitations et des orages sur notre d\u00e9partement. La France se trouvera donc totalement isol\u00e9 des tr\u00e8s fortes chaleurs parfois exceptionnelles dans tout le reste de l&rsquo;Europe, Ce temps perdurera jusqu&rsquo;en premi\u00e8re d\u00e9cade d&rsquo;ao\u00fbt.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"794\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/E7yzb7vX0AE55-4-1024x794.jpg\" alt=\"\" class=\"wp-image-200\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/E7yzb7vX0AE55-4-1024x794.jpg 1024w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/E7yzb7vX0AE55-4-300x233.jpg 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/E7yzb7vX0AE55-4-768x596.jpg 768w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/E7yzb7vX0AE55-4-1536x1192.jpg 1536w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/E7yzb7vX0AE55-4-2048x1589.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Indicateur mensuel G\u00e9op 500Hpa<\/figcaption><\/figure>\n\n\n\n<p>R\u00e9sultat dans l&rsquo;Ain, un mois de juillet sous les normes, \u00e0 Bourg en Bresse sur ma station je rel\u00e8ve un d\u00e9ficit de <strong>-1.3\u00b0C<\/strong> par rapports aux normes (1981-2010) avec une moyenne de<strong> 19.5\u00b0C<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"500\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/VuSVLLg.png\" alt=\"\" class=\"wp-image-198\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/VuSVLLg.png 899w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/VuSVLLg-300x167.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/VuSVLLg-768x427.png 768w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><figcaption>Anomalie temp\u00e9rature juillet 2021<\/figcaption><\/figure>\n\n\n\n<p>Du cot\u00e9 des pr\u00e9cipitations, mois record avec <strong>262.6 mm<\/strong> \u00e0 Bourg en Bresse, en plaine en Bresse il se classe aussi dans<strong>&nbsp;le top<\/strong>&nbsp;des mois les plus arros\u00e9s tout mois confondu en 1ere, 2nd ou 3eme place suivant les stations. <strong>4<\/strong> \u00e9pisodes de plus de 30 mm \/ 24h et <strong>2<\/strong> avec plus de 50 mm\/24h on \u00e9t\u00e9 relev\u00e9s. Cet enchainement d&rsquo;\u00e9pisodes importants ont fait r\u00e9agir les cours d&rsquo;eau, avec des <strong>vigilances pluie\/inondation<\/strong> dans un premier temps suivi de <strong>vigilance crue<\/strong> pour la rivi\u00e8re d&rsquo;Ain.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"896\" height=\"501\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/Al7vNFf.png\" alt=\"\" class=\"wp-image-199\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/Al7vNFf.png 896w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/Al7vNFf-300x168.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/Al7vNFf-768x429.png 768w\" sizes=\"auto, (max-width: 896px) 100vw, 896px\" \/><figcaption>Cumul pluie juillet 2021<\/figcaption><\/figure>\n\n\n\n<pre class=\"wp-block-preformatted\">Ao\u00fbt<\/pre>\n\n\n\n<p>Apr\u00e8s un d\u00e9but du mois d&rsquo;ao\u00fbt dans la lign\u00e9e du mois de juillet avec une premi\u00e8re d\u00e9cade tr\u00e8s humide et fraiche toujours dans une situation de blocage avec une goutte froide, courte p\u00e9riode de chaleur jusqu&rsquo;au 15 ao\u00fbt, puis retour de la fraicheur en flux de nord. La bise soufflera pendant pr\u00e8s de 2 semaines limitant fortement la mont\u00e9e des temp\u00e9ratures et suivant les jours pouvant laisser apparaitre du brouillard et des journ\u00e9es assez nuageuses sous des stratus. <\/p>\n\n\n\n<p>La temp\u00e9rature moyenne a donc \u00e9t\u00e9 de 18.8\u00b0C soir <strong>1.5\u00b0C<\/strong> sous les normes de saison pour un mois d&rsquo;Ao\u00fbt, le plus frais de l&rsquo;\u00e9t\u00e9<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"888\" height=\"499\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/uVFuEyz.png\" alt=\"\" class=\"wp-image-205\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/uVFuEyz.png 888w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/uVFuEyz-300x169.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/uVFuEyz-768x432.png 768w\" sizes=\"auto, (max-width: 888px) 100vw, 888px\" \/><figcaption>Anomalie temp\u00e9rature ao\u00fbt 2021<\/figcaption><\/figure>\n\n\n\n<p><strong>63.8 mm<\/strong> relev\u00e9e \u00e0 Bourg en Bresse sur les 7 premiers jours. Le reste du mois sera beaucoup plus sec, peu ou pas de pluie mesur\u00e9e, \u00e0 peine <strong>5.2 mm<\/strong> sur les 23 derniers jours du mois, ce qui fait donc un total de <strong>69 mm<\/strong> l\u00e9g\u00e8rement inf\u00e9rieur \u00e0 la norme qui se trouve aux alentours des 85 mm. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"496\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/O6NTk6M.png\" alt=\"\" class=\"wp-image-206\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/O6NTk6M.png 902w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/O6NTk6M-300x165.png 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/O6NTk6M-768x422.png 768w\" sizes=\"auto, (max-width: 902px) 100vw, 902px\" \/><figcaption>Cumul de pluie ao\u00fbt 2021<\/figcaption><\/figure>\n\n\n\n<pre class=\"wp-block-preformatted\">Conclusion<\/pre>\n\n\n\n<p>Pour conclure cet \u00e9t\u00e9 2021, 3 nuit tropicales on \u00e9t\u00e9 relev\u00e9es (&gt; 20\u00b0C la nuit) et 11 journ\u00e9e de fortes chaleurs (&gt; 30\u00b0C) aucune journ\u00e9e de tr\u00e8s fortes chaleurs (&gt; 35\u00b0C). Un \u00e9t\u00e9 isol\u00e9 par rapport aux derni\u00e8res ann\u00e9es extr\u00eamement chaudes que l&rsquo;on a connu, un \u00e9t\u00e9 comme on devrait en connaitre tous les ans post r\u00e9chauffement pour les temp\u00e9ratures, que l&rsquo;on connaitra probablement pas ces prochaines ann\u00e9es, il est de plus en plus difficile d&rsquo;avoir des mois plus frais que la normal.<\/p>\n\n\n\n<p>De plus notre \u00e9t\u00e9 avec des temp\u00e9ratures l\u00e9g\u00e8rement sous les normes pour le d\u00e9partement de l&rsquo;Ain,  ne se confirme pas totalement pour l&rsquo;ensemble de la France car en moyenne l&rsquo;\u00e9t\u00e9 2021 se trouve tr\u00e8s l\u00e9g\u00e8rement au-dessus des normes avec +0.4\u00b0C. La France un des seuls pays \u00e0 avoir eu la \u00ab\u00a0chance\u00a0\u00bb d&rsquo;avoir eu des temp\u00e9ratures proches des normes pour cet \u00e9t\u00e9 2021 \u00ab\u00a0bulle de fraicheur\u00a0\u00bb au milieu d&rsquo;un four europ\u00e9en souvent 2 \u00e0 3\u00b0C au-dessus des normes et parfois de nombreux records absolu de chaleurs nationaux et un record europ\u00e9en battu. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC2BYWYAUrmqclwe4.jfif_-1024x576.jpg\" alt=\"\" class=\"wp-image-217\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC2BYWYAUrmqclwe4.jfif_-1024x576.jpg 1024w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC2BYWYAUrmqclwe4.jfif_-300x169.jpg 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC2BYWYAUrmqclwe4.jfif_-768x432.jpg 768w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC2BYWYAUrmqclwe4.jfif_-1536x864.jpg 1536w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC2BYWYAUrmqclwe4.jfif_.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC7zVXEAkgY_Jrlq7.jfif_-1024x576.jpg\" alt=\"\" class=\"wp-image-219\" srcset=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC7zVXEAkgY_Jrlq7.jfif_-1024x576.jpg 1024w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC7zVXEAkgY_Jrlq7.jfif_-300x169.jpg 300w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC7zVXEAkgY_Jrlq7.jfif_-768x432.jpg 768w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC7zVXEAkgY_Jrlq7.jfif_-1536x864.jpg 1536w, https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/09\/E_NC7zVXEAkgY_Jrlq7.jfif_.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9t\u00e9 2021 s&rsquo;ach\u00e8ve avec un mois d&rsquo;ao\u00fbt plus frais que la normale et tr\u00e8s peu de pluie pour les 20 derniers jours. Ce 31 ao\u00fbt marque la fin de l&rsquo;\u00e9t\u00e9 2021 du point de vue m\u00e9t\u00e9orologique, \u00e0 partir du 1er septembre nous commen\u00e7ons l&rsquo;automne. Mais attention, les fortes chaleurs sont toujours possibles, \u00e0 l&rsquo;image de &hellip; <a href=\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&rsquo;Ain<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,7,11],"tags":[],"class_list":["post-191","post","type-post","status-publish","format-standard","hentry","category-chaleur","category-climatologie","category-observation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&#039;Ain - Plan\u00e8te M\u00e9t\u00e9o Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&#039;Ain - Plan\u00e8te M\u00e9t\u00e9o Blog\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;\u00e9t\u00e9 2021 s&rsquo;ach\u00e8ve avec un mois d&rsquo;ao\u00fbt plus frais que la normale et tr\u00e8s peu de pluie pour les 20 derniers jours. Ce 31 ao\u00fbt marque la fin de l&rsquo;\u00e9t\u00e9 2021 du point de vue m\u00e9t\u00e9orologique, \u00e0 partir du 1er septembre nous commen\u00e7ons l&rsquo;automne. Mais attention, les fortes chaleurs sont toujours possibles, \u00e0 l&rsquo;image de &hellip; Continuer la lecture de Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&rsquo;Ain\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\" \/>\n<meta property=\"og:site_name\" content=\"Plan\u00e8te M\u00e9t\u00e9o Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-31T18:17:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T14:50:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png\" \/>\n<meta name=\"author\" content=\"Benji\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benji\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\"},\"author\":{\"name\":\"Benji\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/#\/schema\/person\/9f8b4184457873e167f52653d6a2b9c4\"},\"headline\":\"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&rsquo;Ain\",\"datePublished\":\"2021-08-31T18:17:46+00:00\",\"dateModified\":\"2021-09-01T14:50:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\"},\"wordCount\":1275,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png\",\"articleSection\":[\"Chaleur\",\"Climatologie\",\"Observation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\",\"url\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\",\"name\":\"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l'Ain - Plan\u00e8te M\u00e9t\u00e9o Blog\",\"isPartOf\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png\",\"datePublished\":\"2021-08-31T18:17:46+00:00\",\"dateModified\":\"2021-09-01T14:50:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage\",\"url\":\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png\",\"contentUrl\":\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png\",\"width\":912,\"height\":505},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/planete-meteo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&#8217;Ain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/#website\",\"url\":\"https:\/\/planete-meteo.com\/blog\/\",\"name\":\"Plan\u00e8te M\u00e9t\u00e9o Blog\",\"description\":\"Fil d&#039;actualit\u00e9 m\u00e9t\u00e9o, pr\u00e9visions, observations pour l&#039;Ain\",\"publisher\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/planete-meteo.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/#organization\",\"name\":\"Plan\u00e8te M\u00e9t\u00e9o Blog\",\"url\":\"https:\/\/planete-meteo.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/05\/cropped-cropped-logoPlanete-meteo_rond_500.png\",\"contentUrl\":\"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/05\/cropped-cropped-logoPlanete-meteo_rond_500.png\",\"width\":248,\"height\":248,\"caption\":\"Plan\u00e8te M\u00e9t\u00e9o Blog\"},\"image\":{\"@id\":\"https:\/\/planete-meteo.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/#\/schema\/person\/9f8b4184457873e167f52653d6a2b9c4\",\"name\":\"Benji\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/planete-meteo.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/57bb786c89649ee5e336c8f53eff444c49ed4a158048c7edf8895080b80d27a1?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/57bb786c89649ee5e336c8f53eff444c49ed4a158048c7edf8895080b80d27a1?s=96&d=retro&r=g\",\"caption\":\"Benji\"},\"sameAs\":[\"http:\/\/planete-meteo.com\/blog\"],\"url\":\"https:\/\/planete-meteo.com\/blog\/author\/benji\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l'Ain - Plan\u00e8te M\u00e9t\u00e9o Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/","og_locale":"fr_FR","og_type":"article","og_title":"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l'Ain - Plan\u00e8te M\u00e9t\u00e9o Blog","og_description":"L&rsquo;\u00e9t\u00e9 2021 s&rsquo;ach\u00e8ve avec un mois d&rsquo;ao\u00fbt plus frais que la normale et tr\u00e8s peu de pluie pour les 20 derniers jours. Ce 31 ao\u00fbt marque la fin de l&rsquo;\u00e9t\u00e9 2021 du point de vue m\u00e9t\u00e9orologique, \u00e0 partir du 1er septembre nous commen\u00e7ons l&rsquo;automne. Mais attention, les fortes chaleurs sont toujours possibles, \u00e0 l&rsquo;image de &hellip; Continuer la lecture de Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&rsquo;Ain","og_url":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/","og_site_name":"Plan\u00e8te M\u00e9t\u00e9o Blog","article_published_time":"2021-08-31T18:17:46+00:00","article_modified_time":"2021-09-01T14:50:01+00:00","og_image":[{"url":"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png"}],"author":"Benji","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Benji","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#article","isPartOf":{"@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/"},"author":{"name":"Benji","@id":"https:\/\/planete-meteo.com\/blog\/#\/schema\/person\/9f8b4184457873e167f52653d6a2b9c4"},"headline":"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&rsquo;Ain","datePublished":"2021-08-31T18:17:46+00:00","dateModified":"2021-09-01T14:50:01+00:00","mainEntityOfPage":{"@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/"},"wordCount":1275,"commentCount":0,"publisher":{"@id":"https:\/\/planete-meteo.com\/blog\/#organization"},"image":{"@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage"},"thumbnailUrl":"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png","articleSection":["Chaleur","Climatologie","Observation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/","url":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/","name":"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l'Ain - Plan\u00e8te M\u00e9t\u00e9o Blog","isPartOf":{"@id":"https:\/\/planete-meteo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage"},"image":{"@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage"},"thumbnailUrl":"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png","datePublished":"2021-08-31T18:17:46+00:00","dateModified":"2021-09-01T14:50:01+00:00","breadcrumb":{"@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#primaryimage","url":"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png","contentUrl":"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/08\/n6Vr3AB.png","width":912,"height":505},{"@type":"BreadcrumbList","@id":"https:\/\/planete-meteo.com\/blog\/2021\/08\/31\/ete-2021-temperatures-legerement-sous-les-normes-et-tres-humide-dans-lain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/planete-meteo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Et\u00e9 2021 ? Temp\u00e9ratures l\u00e9g\u00e8rement sous les normes et tr\u00e8s humide dans l&#8217;Ain"}]},{"@type":"WebSite","@id":"https:\/\/planete-meteo.com\/blog\/#website","url":"https:\/\/planete-meteo.com\/blog\/","name":"Plan\u00e8te M\u00e9t\u00e9o Blog","description":"Fil d&#039;actualit\u00e9 m\u00e9t\u00e9o, pr\u00e9visions, observations pour l&#039;Ain","publisher":{"@id":"https:\/\/planete-meteo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planete-meteo.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/planete-meteo.com\/blog\/#organization","name":"Plan\u00e8te M\u00e9t\u00e9o Blog","url":"https:\/\/planete-meteo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/planete-meteo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/05\/cropped-cropped-logoPlanete-meteo_rond_500.png","contentUrl":"https:\/\/planete-meteo.com\/blog\/wp-content\/uploads\/2021\/05\/cropped-cropped-logoPlanete-meteo_rond_500.png","width":248,"height":248,"caption":"Plan\u00e8te M\u00e9t\u00e9o Blog"},"image":{"@id":"https:\/\/planete-meteo.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/planete-meteo.com\/blog\/#\/schema\/person\/9f8b4184457873e167f52653d6a2b9c4","name":"Benji","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/planete-meteo.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/57bb786c89649ee5e336c8f53eff444c49ed4a158048c7edf8895080b80d27a1?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57bb786c89649ee5e336c8f53eff444c49ed4a158048c7edf8895080b80d27a1?s=96&d=retro&r=g","caption":"Benji"},"sameAs":["http:\/\/planete-meteo.com\/blog"],"url":"https:\/\/planete-meteo.com\/blog\/author\/benji\/"}]}},"_links":{"self":[{"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/posts\/191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/comments?post=191"}],"version-history":[{"count":10,"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/posts\/191\/revisions"}],"predecessor-version":[{"id":353,"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/posts\/191\/revisions\/353"}],"wp:attachment":[{"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/media?parent=191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/categories?post=191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/planete-meteo.com\/blog\/wp-json\/wp\/v2\/tags?post=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}